{"id":67082,"date":"2024-04-16T08:40:58","date_gmt":"2024-04-16T08:40:58","guid":{"rendered":"https:\/\/fundacionrafanadal.quelinka.es\/?p=67082"},"modified":"2026-01-30T11:43:17","modified_gmt":"2026-01-30T11:43:17","slug":"exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid","status":"publish","type":"post","link":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/","title":{"rendered":"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En conmemoraci\u00f3n del <strong>D\u00eda del Deporte para el Desarrollo y la Paz<\/strong> que se celebr\u00f3 el 6 de abril, el <a href=\"https:\/\/www.fundacionrafanadal.quelinka.es\/que-hacemos\/proyectos\/centros-fundacion-rafa-nadal\/\">Centro Fundaci\u00f3n Rafa Nadal de Madrid<\/a> acogi\u00f3 ayer una emocionante jornada deportiva con un enfoque especial en la perspectiva de g\u00e9nero. El evento fue organizado en colaboraci\u00f3n con las entidades que integran la <strong>Mesa Infanto-Juvenil de San Ferm\u00edn.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad tuvo lugar en las pistas deportivas Eloy del Moral Garc\u00eda del Parque Lineal del Manzanares, de 17.00 a 19.30 horas, y cont\u00f3 con la participaci\u00f3n de diferentes personas, incluyendo<em> ni\u00f1as, adolescentes y sus familias.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la jornada, se llevaron a cabo siete disciplinas deportivas dirigidas por profesionales de diversas entidades, con la colaboraci\u00f3n activa de j\u00f3venes adolescentes. Estas disciplinas incluyeron <em>b\u00e1dminton, b\u00e9isbol, crossfit, baloncesto, f\u00fatbol 7, wushu y juegos motrices.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1713\" height=\"1370\" data-id=\"19932\" src=\"https:\/\/www.fundacionrafanadal.quelinka.es\/wp-content\/uploads\/2024\/04\/0001-1.jpg\" alt=\"\" class=\"wp-image-19932\" srcset=\"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1.jpg 1713w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1-300x240.jpg 300w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1-768x614.jpg 768w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1-1024x819.jpg 1024w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1-1536x1228.jpg 1536w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1-900x720.jpg 900w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0001-1-44x35.jpg 44w\" sizes=\"auto, (max-width: 1713px) 100vw, 1713px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1090\" height=\"872\" data-id=\"19935\" src=\"https:\/\/www.fundacionrafanadal.quelinka.es\/wp-content\/uploads\/2024\/04\/0002.jpg\" alt=\"\" class=\"wp-image-19935\" srcset=\"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0002.jpg 1090w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0002-300x240.jpg 300w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0002-768x614.jpg 768w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0002-1024x819.jpg 1024w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0002-900x720.jpg 900w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0002-44x35.jpg 44w\" sizes=\"auto, (max-width: 1090px) 100vw, 1090px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1200\" data-id=\"19938\" src=\"https:\/\/www.fundacionrafanadal.quelinka.es\/wp-content\/uploads\/2024\/04\/0003.jpg\" alt=\"\" class=\"wp-image-19938\" srcset=\"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0003.jpg 1500w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0003-300x240.jpg 300w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0003-768x614.jpg 768w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0003-1024x819.jpg 1024w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0003-900x720.jpg 900w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0003-44x35.jpg 44w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1184\" height=\"948\" data-id=\"19941\" src=\"https:\/\/www.fundacionrafanadal.quelinka.es\/wp-content\/uploads\/2024\/04\/0004-1.jpg\" alt=\"\" class=\"wp-image-19941\" srcset=\"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0004-1.jpg 1184w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0004-1-300x240.jpg 300w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0004-1-768x615.jpg 768w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0004-1-1024x820.jpg 1024w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0004-1-900x721.jpg 900w, https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/0004-1-44x35.jpg 44w\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro Fundaci\u00f3n Rafa Nadal de Madrid estuvo a cargo de la coordinaci\u00f3n de tres actividades principales: <strong>b\u00e1dminton, b\u00e9isbol y crossfit<\/strong>. Cada participante recibi\u00f3 un pasaporte de participaci\u00f3n, el cual fue sellado por la responsable de cada actividad al finalizar el juego. Aquellos que lograron obtener al menos cuatro de los siete sellos recibieron un diploma de participaci\u00f3n, que fue entregado al t\u00e9rmino de la jornada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00abEsta jornada fue una excelente oportunidad para promover la inclusi\u00f3n y la igualdad de g\u00e9nero a trav\u00e9s del deporte\u00bb,<\/em> destacan los profesionales del centro. <em>\u00abFue inspirador ver a personas de todas las edades y g\u00e9neros disfrutar juntos de una tarde llena de actividad f\u00edsica y diversi\u00f3n\u00bb.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada concluy\u00f3 con una merienda compartida, donde todos los participantes tuvieron la oportunidad de intercambiar experiencias y fortalecer v\u00ednculos comunitarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Fundaci\u00f3n Rafa Nadal<\/strong> agradece a todas las entidades colaboradoras y a los participantes por hacer de esta jornada una experiencia memorable, fomentando valores de <em>solidaridad, respeto y trabajo en equipo<\/em> a trav\u00e9s del deporte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conmemoraci\u00f3n del D\u00eda del Deporte para el Desarrollo y la Paz que se celebr\u00f3 el 6 de abril, el Centro Fundaci\u00f3n Rafa Nadal de Madrid acogi\u00f3 ayer una emocionante jornada deportiva con un enfoque especial en la perspectiva de g\u00e9nero. El evento fue organizado en colaboraci\u00f3n con las entidades que integran la Mesa Infanto-Juvenil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[1298],"class_list":["post-67082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-tenis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid - Fundaci\u00f3n Rafa Nadal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid - Fundaci\u00f3n Rafa Nadal\" \/>\n<meta property=\"og:description\" content=\"En conmemoraci\u00f3n del D\u00eda del Deporte para el Desarrollo y la Paz que se celebr\u00f3 el 6 de abril, el Centro Fundaci\u00f3n Rafa Nadal de Madrid acogi\u00f3 ayer una emocionante jornada deportiva con un enfoque especial en la perspectiva de g\u00e9nero. El evento fue organizado en colaboraci\u00f3n con las entidades que integran la Mesa Infanto-Juvenil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Rafa Nadal\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T08:40:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T11:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/IMG_5908_b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#\\\/schema\\\/person\\\/8a3319731657591d181081b6350bb1e2\"},\"headline\":\"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid\",\"datePublished\":\"2024-04-16T08:40:58+00:00\",\"dateModified\":\"2026-01-30T11:43:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/\"},\"wordCount\":339,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_5908_b.jpg\",\"keywords\":[\"Tenis\"],\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/\",\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/\",\"name\":\"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid - Fundaci\u00f3n Rafa Nadal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_5908_b.jpg\",\"datePublished\":\"2024-04-16T08:40:58+00:00\",\"dateModified\":\"2026-01-30T11:43:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#\\\/schema\\\/person\\\/8a3319731657591d181081b6350bb1e2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_5908_b.jpg\",\"contentUrl\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG_5908_b.jpg\",\"width\":1000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/\",\"name\":\"Fundaci\u00f3n Rafa Nadal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#\\\/schema\\\/person\\\/8a3319731657591d181081b6350bb1e2\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.fundacionrafanadal.quelinka.es\"],\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/author\\\/dev_25_quelinka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid - Fundaci\u00f3n Rafa Nadal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/","og_locale":"ca_ES","og_type":"article","og_title":"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid - Fundaci\u00f3n Rafa Nadal","og_description":"En conmemoraci\u00f3n del D\u00eda del Deporte para el Desarrollo y la Paz que se celebr\u00f3 el 6 de abril, el Centro Fundaci\u00f3n Rafa Nadal de Madrid acogi\u00f3 ayer una emocionante jornada deportiva con un enfoque especial en la perspectiva de g\u00e9nero. El evento fue organizado en colaboraci\u00f3n con las entidades que integran la Mesa Infanto-Juvenil [&hellip;]","og_url":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/","og_site_name":"Fundaci\u00f3n Rafa Nadal","article_published_time":"2024-04-16T08:40:58+00:00","article_modified_time":"2026-01-30T11:43:17+00:00","og_image":[{"width":1000,"height":800,"url":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/IMG_5908_b.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#article","isPartOf":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/"},"author":{"name":"admin","@id":"https:\/\/fundacionrafanadal.org\/ca\/#\/schema\/person\/8a3319731657591d181081b6350bb1e2"},"headline":"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid","datePublished":"2024-04-16T08:40:58+00:00","dateModified":"2026-01-30T11:43:17+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/"},"wordCount":339,"commentCount":0,"image":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/IMG_5908_b.jpg","keywords":["Tenis"],"articleSection":["Sin categor\u00eda"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/","url":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/","name":"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid - Fundaci\u00f3n Rafa Nadal","isPartOf":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#primaryimage"},"image":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/IMG_5908_b.jpg","datePublished":"2024-04-16T08:40:58+00:00","dateModified":"2026-01-30T11:43:17+00:00","author":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/#\/schema\/person\/8a3319731657591d181081b6350bb1e2"},"breadcrumb":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#primaryimage","url":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/IMG_5908_b.jpg","contentUrl":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2024\/04\/IMG_5908_b.jpg","width":1000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionrafanadal.org\/ca\/exitosa-jornada-esportiva-amb-enfocament-de-genere-al-centre-fundacio-rafa-nadal-de-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionrafanadal.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Exitosa jornada esportiva amb enfocament de g\u00e8nere al Centre Fundaci\u00f3 Rafa Nadal de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/fundacionrafanadal.org\/ca\/#website","url":"https:\/\/fundacionrafanadal.org\/ca\/","name":"Fundaci\u00f3n Rafa Nadal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionrafanadal.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/fundacionrafanadal.org\/ca\/#\/schema\/person\/8a3319731657591d181081b6350bb1e2","name":"admin","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.fundacionrafanadal.quelinka.es"],"url":"https:\/\/fundacionrafanadal.org\/ca\/author\/dev_25_quelinka\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts\/67082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/comments?post=67082"}],"version-history":[{"count":0,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts\/67082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/media\/67081"}],"wp:attachment":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/media?parent=67082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/categories?post=67082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/tags?post=67082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}