{"id":68809,"date":"2020-05-20T15:38:13","date_gmt":"2020-05-20T15:38:13","guid":{"rendered":"https:\/\/www.fundacionrafanadal.org\/?p=68809"},"modified":"2026-02-19T11:23:24","modified_gmt":"2026-02-19T11:23:24","slug":"juego-y-aire-libre-un-tandem-necesario","status":"publish","type":"post","link":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/","title":{"rendered":"Juego y aire libre: un t\u00e1ndem necesario"},"content":{"rendered":"<p>El desarrollo sensorial, cognitivo, emocional\u2026que como humanos llevamos a cabo durante la infancia se realiza en gran medida mediante el juego, sobre todo si este es al aire libre y, m\u00e1s a\u00fan, en entornos naturales. Sin embargo, las estad\u00edsticas -previas a la situaci\u00f3n de confinamiento- hablan por si solas: el 82% de los ni\u00f1os en Espa\u00f1a juega al aire libre menos tiempo del recomendado. Es decir: 4 de cada 5.<\/p>\n<p>Seg\u00fan una investigaci\u00f3n llevada a cabo por el Instituto Tecnol\u00f3gico de producto infantil y de ocio\u2013AIJU, cuanto m\u00e1s peque\u00f1os, m\u00e1s tiempo se recomienda de juego al aire libre. As\u00ed, de 0 a 3 a\u00f1os \u00e9ste es de 2 horas; de 4 a 6 a\u00f1os de 1,30 horas; de 7 a 9 a\u00f1os, de 1,15 horas, y de 10 a 12 a\u00f1os, se recomienda que jueguen en el exterior un m\u00ednimo de una hora.<\/p>\n<p>Pero los datos previos a Covid-19 reflejan otra realidad. Aunque los ni\u00f1os de 0 a 3 a\u00f1os son los que m\u00e1s juegan al aire libre, s\u00f3lo el 35% alcanza el tiempo recomendado, siendo la media de 1,25 horas. Por el contrario, los ni\u00f1os de 10 a 12 a\u00f1os son los que menos juegan al aire libre; un 94% juegan al exterior por debajo del tiempo recomendado, con una media de 35 minutos.<\/p>\n<p>\u201c<em>El juego debe ser la principal actividad de un ni\u00f1o. Es lo que su cerebro espera: juegos y m\u00e1s juegos, sobre todo relacionados con la actividad f\u00edsica y preferiblemente al aire libre. Se puede jugar solo \u2013adem\u00e1s, el cerebro tambi\u00e9n necesita aprender a aburrirse- y, sobre todo, en compa\u00f1\u00eda. Cuanto m\u00e1s heterog\u00e9neas sean las edades de los ni\u00f1os que juegan, mejor ser\u00e1 para el desarrollo de las relaciones personales, la modulaci\u00f3n de la agresividad o la empat\u00eda<\/em>\u201d, leemos en este <a href=\"https:\/\/elpais.com\/elpais\/2018\/03\/15\/mamas_papas\/1521111527_411316.html\" target=\"_blank\" rel=\"noopener\">art\u00edculo de El Pa\u00eds<\/a>.<\/p>\n<p>Queda claro entonces de que los beneficios de jugar al aire libre son muchos: ejercicio f\u00edsico, estimulaci\u00f3n de la creatividad, fomento de la sociabilizaci\u00f3n, descubierta del entorno, aprendizaje sobre la naturaleza\u2026En definitiva: jugar al aire libre es sin\u00f3nimo de equilibrio entre el desarrollo f\u00edsico y el intelectual.<\/p>\n<p>Aunque en la situaci\u00f3n actual las salidas de los ni\u00f1os est\u00e1n limitadas a cierta duraci\u00f3n y distancia, vamos a aprovecharlas al m\u00e1ximo para que los m\u00e1s peque\u00f1os puedan ejercitarse, jugar y divertirse. As\u00ed, estaremos a su vez fomentando su desarrollo.<\/p>\n<p>Pero sobre todo: no olvidemos la importancia de ser responsables y cumplir las normas y horarios establecidos en cada fase y\/o territorio. Por el bien de todos.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El desarrollo sensorial, cognitivo, emocional\u2026que como humanos llevamos a cabo durante la infancia se realiza en gran medida mediante el juego, sobre todo si este es al aire libre y, m\u00e1s a\u00fan, en entornos naturales. Sin embargo, las estad\u00edsticas -previas a la situaci\u00f3n de confinamiento- hablan por si solas: el 82% de los ni\u00f1os en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-68809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juego y aire libre: un t\u00e1ndem necesario - Fundaci\u00f3n Rafa Nadal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juego y aire libre: un t\u00e1ndem necesario - Fundaci\u00f3n Rafa Nadal\" \/>\n<meta property=\"og:description\" content=\"El desarrollo sensorial, cognitivo, emocional\u2026que como humanos llevamos a cabo durante la infancia se realiza en gran medida mediante el juego, sobre todo si este es al aire libre y, m\u00e1s a\u00fan, en entornos naturales. Sin embargo, las estad\u00edsticas -previas a la situaci\u00f3n de confinamiento- hablan por si solas: el 82% de los ni\u00f1os en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Rafa Nadal\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-20T15:38:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T11:23:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2020\/05\/thumbnail_large-1-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#\\\/schema\\\/person\\\/8a3319731657591d181081b6350bb1e2\"},\"headline\":\"Juego y aire libre: un t\u00e1ndem necesario\",\"datePublished\":\"2020-05-20T15:38:13+00:00\",\"dateModified\":\"2026-02-19T11:23:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/\"},\"wordCount\":451,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/thumbnail_large-1-1-1.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/\",\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/\",\"name\":\"Juego y aire libre: un t\u00e1ndem necesario - Fundaci\u00f3n Rafa Nadal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/thumbnail_large-1-1-1.jpg\",\"datePublished\":\"2020-05-20T15:38:13+00:00\",\"dateModified\":\"2026-02-19T11:23:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#\\\/schema\\\/person\\\/8a3319731657591d181081b6350bb1e2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/thumbnail_large-1-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fundacionrafanadal.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/thumbnail_large-1-1-1.jpg\",\"width\":550,\"height\":367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/juego-y-aire-libre-un-tandem-necesario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juego y aire libre: un t\u00e1ndem necesario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/\",\"name\":\"Fundaci\u00f3n Rafa Nadal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/#\\\/schema\\\/person\\\/8a3319731657591d181081b6350bb1e2\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.fundacionrafanadal.quelinka.es\"],\"url\":\"https:\\\/\\\/fundacionrafanadal.org\\\/ca\\\/author\\\/dev_25_quelinka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juego y aire libre: un t\u00e1ndem necesario - Fundaci\u00f3n Rafa Nadal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/","og_locale":"ca_ES","og_type":"article","og_title":"Juego y aire libre: un t\u00e1ndem necesario - Fundaci\u00f3n Rafa Nadal","og_description":"El desarrollo sensorial, cognitivo, emocional\u2026que como humanos llevamos a cabo durante la infancia se realiza en gran medida mediante el juego, sobre todo si este es al aire libre y, m\u00e1s a\u00fan, en entornos naturales. Sin embargo, las estad\u00edsticas -previas a la situaci\u00f3n de confinamiento- hablan por si solas: el 82% de los ni\u00f1os en [&hellip;]","og_url":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/","og_site_name":"Fundaci\u00f3n Rafa Nadal","article_published_time":"2020-05-20T15:38:13+00:00","article_modified_time":"2026-02-19T11:23:24+00:00","og_image":[{"width":550,"height":367,"url":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2020\/05\/thumbnail_large-1-1-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#article","isPartOf":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/"},"author":{"name":"admin","@id":"https:\/\/fundacionrafanadal.org\/ca\/#\/schema\/person\/8a3319731657591d181081b6350bb1e2"},"headline":"Juego y aire libre: un t\u00e1ndem necesario","datePublished":"2020-05-20T15:38:13+00:00","dateModified":"2026-02-19T11:23:24+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/"},"wordCount":451,"commentCount":0,"image":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2020\/05\/thumbnail_large-1-1-1.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/","url":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/","name":"Juego y aire libre: un t\u00e1ndem necesario - Fundaci\u00f3n Rafa Nadal","isPartOf":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#primaryimage"},"image":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2020\/05\/thumbnail_large-1-1-1.jpg","datePublished":"2020-05-20T15:38:13+00:00","dateModified":"2026-02-19T11:23:24+00:00","author":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/#\/schema\/person\/8a3319731657591d181081b6350bb1e2"},"breadcrumb":{"@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#primaryimage","url":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2020\/05\/thumbnail_large-1-1-1.jpg","contentUrl":"https:\/\/fundacionrafanadal.org\/wp-content\/uploads\/2020\/05\/thumbnail_large-1-1-1.jpg","width":550,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionrafanadal.org\/ca\/juego-y-aire-libre-un-tandem-necesario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionrafanadal.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Juego y aire libre: un t\u00e1ndem necesario"}]},{"@type":"WebSite","@id":"https:\/\/fundacionrafanadal.org\/ca\/#website","url":"https:\/\/fundacionrafanadal.org\/ca\/","name":"Fundaci\u00f3n Rafa Nadal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionrafanadal.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/fundacionrafanadal.org\/ca\/#\/schema\/person\/8a3319731657591d181081b6350bb1e2","name":"admin","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3483bd3d78901c0c4472aa9769f3346cb2beee3e7af07fb98f33bdedf49f89dd?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.fundacionrafanadal.quelinka.es"],"url":"https:\/\/fundacionrafanadal.org\/ca\/author\/dev_25_quelinka\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts\/68809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/comments?post=68809"}],"version-history":[{"count":1,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts\/68809\/revisions"}],"predecessor-version":[{"id":68810,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/posts\/68809\/revisions\/68810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/media\/68808"}],"wp:attachment":[{"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/media?parent=68809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/categories?post=68809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionrafanadal.org\/ca\/wp-json\/wp\/v2\/tags?post=68809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}